{"id":9101,"date":"2025-09-04T18:50:36","date_gmt":"2025-09-05T01:50:36","guid":{"rendered":"https:\/\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png"},"modified":"2025-09-04T18:53:12","modified_gmt":"2025-09-05T01:53:12","slug":"kaylee-firefly-youre-gonna-come-with-us-browncoat-ball-2025-los-angeles-ca","status":"inherit","type":"attachment","link":"https:\/\/browncoatball.com\/2025\/schedule\/kaylee-firefly-youre-gonna-come-with-us-browncoat-ball-2025-los-angeles-ca\/","title":{"rendered":"Kaylee &#8211; Firefly &#8211; You&#8217;re gonna come with us &#8211; Browncoat Ball 2025 &#8211; Los Angeles CA"},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-9101","attachment","type-attachment","status-inherit","hentry","wpautop"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/agmpeM-2mN","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"156\" src=\"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?fit=300%2C156&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Kaylee - Firefly - You&#039;re gonna come with us - Browncoat Ball 2025 - Los Angeles CA\" srcset=\"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?resize=300%2C156&amp;ssl=1 300w, https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?resize=150%2C78&amp;ssl=1 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Kaylee &#8211; Firefly &#8211; You&#8217;re gonna come with us &#8211; Browncoat Ball 2025 &#8211; Los Angeles CA<\/p>\n"},"caption":{"rendered":"<p>Kaylee &#8211; Firefly &#8211; You&#8217;re gonna come with us &#8211; Browncoat Ball 2025 &#8211; Los Angeles CA<\/p>\n"},"alt_text":"Kaylee - Firefly - You're gonna come with us - Browncoat Ball 2025 - Los Angeles CA","media_type":"image","mime_type":"image\/png","media_details":{"width":700,"height":364,"file":"2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png","filesize":292864,"sizes":{"medium":{"file":"Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA-300x156.png","width":300,"height":156,"filesize":32734,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?fit=300%2C156&ssl=1"},"thumbnail":{"file":"Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA-150x150.png","width":150,"height":150,"filesize":18199,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?resize=150%2C150&ssl=1"},"post-thumbnail":{"file":"Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA-672x364.png","width":672,"height":364,"filesize":104722,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?resize=672%2C364&ssl=1"},"woocommerce_thumbnail":{"file":"Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA-150x78.png","width":150,"height":78,"filesize":11135,"uncropped":true,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?fit=150%2C78&ssl=1"},"woocommerce_single":{"file":"Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA-300x156.png","width":300,"height":156,"filesize":32734,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?fit=300%2C156&ssl=1"},"woocommerce_gallery_thumbnail":{"file":"Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA-100x100.png","width":100,"height":100,"filesize":9717,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?resize=100%2C100&ssl=1"},"full":{"file":"Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?fit=700%2C364&ssl=1","width":700,"height":364,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png?fit=700%2C364&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5322,"source_url":"https:\/\/browncoatball.com\/2025\/wp-content\/uploads\/2025\/09\/Kaylee-Firefly-Youre-gonna-come-with-us-Browncoat-Ball-2025-Los-Angeles-CA.png","_links":{"self":[{"href":"https:\/\/browncoatball.com\/2025\/wp-json\/wp\/v2\/media\/9101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/browncoatball.com\/2025\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/browncoatball.com\/2025\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/browncoatball.com\/2025\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/browncoatball.com\/2025\/wp-json\/wp\/v2\/comments?post=9101"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":5322,"href":"https:\/\/browncoatball.com\/2025\/wp-json\/wp\/v2\/pages\/5322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}